


























































{"id":193926,"date":"2026-06-24T14:53:25","date_gmt":"2026-06-24T19:53:25","guid":{"rendered":"https:\/\/losmejorescolegios.com\/co\/?p=193926"},"modified":"2026-06-30T11:44:41","modified_gmt":"2026-06-30T16:44:41","slug":"mde-challenge-jovenes-transforman-medellin-3","status":"publish","type":"post","link":"https:\/\/losmejorescolegios.com\/co\/noticias\/mde-challenge-jovenes-transforman-medellin-3\/","title":{"rendered":"MDE Challenge: Colegio San Jos\u00e9 de Las Vegas transforma Medell\u00edn"},"content":{"rendered":"<h2><b>MDE Challenge: Colegio San Jo<\/b><b>s\u00e9 de Las Vegas transforma Medell\u00edn<\/b><\/h2>\n<h5><b>MDE Challenge y la transformaci\u00f3n de Medell\u00edn<\/b><\/h5>\n<p><b>MDE Challenge<\/b><span style=\"font-weight: 400;\"> es una iniciativa creada por la Organizaci\u00f3n San Jos\u00e9 de Las Vegas con el prop\u00f3sito de conectar a los j\u00f3venes con las realidades de Medell\u00edn y convertirlos en protagonistas de la transformaci\u00f3n social. A trav\u00e9s de esta experiencia, estudiantes de diferentes instituciones educativas analizan problem\u00e1ticas reales de la ciudad y desarrollan propuestas innovadoras para generar un impacto positivo en sus comunidades.<\/span><\/p>\n<h5><b>Retos sociales, ambientales y educativos<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">Durante esta edici\u00f3n, m\u00e1s de 300 j\u00f3venes pertenecientes a 60 instituciones educativas p\u00fablicas, privadas e internacionales trabajaron de manera colaborativa para abordar desaf\u00edos relacionados con el medio ambiente, la educaci\u00f3n, la inclusi\u00f3n social, la convivencia y la calidad de vida. La iniciativa promovi\u00f3 una mirada cr\u00edtica, humana y creativa frente a situaciones que afectan a miles de personas en Medell\u00edn y el Valle de Aburr\u00e1.<\/span><\/p>\n<h5><b>Aliados estrat\u00e9gicos para potenciar el talento juvenil<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">La experiencia incluy\u00f3 recorridos por diferentes espacios emblem\u00e1ticos de la ciudad, convertidos en escenarios de observaci\u00f3n, investigaci\u00f3n y cocreaci\u00f3n. Adem\u00e1s, expertos de organizaciones como EAFIT, CES y Bancolombia acompa\u00f1aron el proceso brindando orientaci\u00f3n t\u00e9cnica y estrat\u00e9gica a los equipos participantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El proyecto culmin\u00f3 en el Centro de Innovaci\u00f3n del Maestro \u2013 Mova, donde los estudiantes presentaron sus propuestas ante expertos y aliados. De esta manera, <\/span><b>MDE Challenge<\/b><span style=\"font-weight: 400;\"> se consolida como una plataforma de liderazgo juvenil que demuestra c\u00f3mo las nuevas generaciones ya est\u00e1n construyendo soluciones para una Medell\u00edn m\u00e1s sostenible, equitativa e incluyente.<\/span><\/p>\n<h5><b>Conozca m\u00e1s sobre esta instituci\u00f3n<\/b><\/h5>\n<p><span style=\"font-weight: 400;\">Si quieres conocer m\u00e1s sobre la <\/span><b>Organizaci\u00f3n San Jos\u00e9 de Las Vegas<\/b><span style=\"font-weight: 400;\">, sus proyectos de innovaci\u00f3n educativa, programas acad\u00e9micos y experiencias de aprendizaje transformador, visita su perfil en <\/span><a href=\"https:\/\/losmejorescolegios.com\/co\/colegio\/colegio-san-jose-de-las-vegas-el-retiro\/\"><b>losmejorescolegios.com<\/b><\/a><span style=\"font-weight: 400;\">, All\u00ed encontrar\u00e1 informaci\u00f3n actualizada sobre una instituci\u00f3n comprometida con la formaci\u00f3n de l\u00edderes capaces de generar impacto positivo en la sociedad.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MDE Challenge: Colegio San Jos\u00e9 de Las Vegas transforma Medell\u00edn MDE Challenge y la transformaci\u00f3n de Medell\u00edn MDE Challenge es una iniciativa creada por la Organizaci\u00f3n San Jos\u00e9 de Las Vegas con el prop\u00f3sito de conectar a los j\u00f3venes con las realidades de Medell\u00edn y convertirlos en protagonistas de la transformaci\u00f3n social. A trav\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":193924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1592],"tags":[5252,6175,3324,3682,6172,6174,6173],"class_list":["post-193926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-colegio-san-jose-de-las-vegas-sede-el-retiro","tag-colegio-san-jose-de-las-vegas-el-retiro","tag-innovacion-educativa","tag-liderazgo-juvenil","tag-organizacion-san-jose-de-las-vegas","tag-san-jose-de-las-vegas-sede-el-retiro","tag-transformacion-social-educacion-en-medellin"],"acf":[],"_links":{"self":[{"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/posts\/193926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/comments?post=193926"}],"version-history":[{"count":3,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/posts\/193926\/revisions"}],"predecessor-version":[{"id":193929,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/posts\/193926\/revisions\/193929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/media\/193924"}],"wp:attachment":[{"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/media?parent=193926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/categories?post=193926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losmejorescolegios.com\/co\/wp-json\/wp\/v2\/tags?post=193926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}